{"id":9496,"date":"2026-05-05T11:52:10","date_gmt":"2026-05-05T14:52:10","guid":{"rendered":"https:\/\/elpueblonoticia.com.ar\/web\/?p=9496"},"modified":"2026-05-05T11:57:25","modified_gmt":"2026-05-05T14:57:25","slug":"ultimo-momento-hallaron-a-nahua-santos-sano-y-salvo","status":"publish","type":"post","link":"https:\/\/elpueblonoticia.com.ar\/web\/2026\/05\/05\/ultimo-momento-hallaron-a-nahua-santos-sano-y-salvo\/","title":{"rendered":"\u00daLTIMO MOMENTO | HALLARON A NAHU\u00c1 SANTOS SANO Y SALVO"},"content":{"rendered":"<p>Tras horas de intensa b\u00fasqueda, el menor Nahu\u00e1 Santos fue encontrado en una zona rural cercana al paraje Duraznillo. De acuerdo a la informaci\u00f3n oficial, estaba acompa\u00f1ado por su padre y ambos se encuentran en buenas condiciones de salud.<\/p>\n<p>El hallazgo se produjo en un sector ubicado entre las localidades de Esquina y Goya, lo que llev\u00f3 tranquilidad a familiares y vecinos que segu\u00edan con preocupaci\u00f3n el desarrollo del caso.<\/p>\n<p>El operativo cont\u00f3 con la participaci\u00f3n de diversas unidades policiales que trabajaron en el \u00e1rea desde el inicio del procedimiento. Las actuaciones en el lugar estuvieron supervisadas por autoridades de seguridad de la regi\u00f3n.<\/p>\n<p>Este resultado representa un avance importante en la investigaci\u00f3n, que hab\u00eda generado gran impacto en la comunidad tras los hechos previos que dieron origen a la b\u00fasqueda. Por estas horas, contin\u00faan las tareas para esclarecer lo ocurrido y determinar los pasos a seguir en el marco de la causa. La confirmaci\u00f3n de que el menor fue encontrado en buen estado trae alivio a toda la provincia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tras horas de intensa b\u00fasqueda, el menor Nahu\u00e1 Santos fue encontrado en una zona rural cercana al paraje Duraznillo. De acuerdo a la informaci\u00f3n oficial, estaba acompa\u00f1ado por su padre y ambos se encuentran en buenas condiciones de salud. El hallazgo se produjo en un sector ubicado entre las localidades de Esquina y Goya, lo [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":9501,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[68],"tags":[],"class_list":["post-9496","post","type-post","status-publish","format-standard","has-post-thumbnail","category-policiales-nacionales"],"_links":{"self":[{"href":"https:\/\/elpueblonoticia.com.ar\/web\/wp-json\/wp\/v2\/posts\/9496","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elpueblonoticia.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elpueblonoticia.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elpueblonoticia.com.ar\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/elpueblonoticia.com.ar\/web\/wp-json\/wp\/v2\/comments?post=9496"}],"version-history":[{"count":0,"href":"https:\/\/elpueblonoticia.com.ar\/web\/wp-json\/wp\/v2\/posts\/9496\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elpueblonoticia.com.ar\/web\/wp-json\/wp\/v2\/media\/9501"}],"wp:attachment":[{"href":"https:\/\/elpueblonoticia.com.ar\/web\/wp-json\/wp\/v2\/media?parent=9496"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elpueblonoticia.com.ar\/web\/wp-json\/wp\/v2\/categories?post=9496"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elpueblonoticia.com.ar\/web\/wp-json\/wp\/v2\/tags?post=9496"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}