{"id":9484,"date":"2026-05-05T10:12:22","date_gmt":"2026-05-05T13:12:22","guid":{"rendered":"https:\/\/elpueblonoticia.com.ar\/web\/?p=9484"},"modified":"2026-05-05T10:12:22","modified_gmt":"2026-05-05T13:12:22","slug":"policiales-en-libres-robaron-una-moto-titan-del-hall-de-una-casa-y-un-policia-de-civil-detuvo-a-un-ladron-en-bicicleta","status":"publish","type":"post","link":"https:\/\/elpueblonoticia.com.ar\/web\/2026\/05\/05\/policiales-en-libres-robaron-una-moto-titan-del-hall-de-una-casa-y-un-policia-de-civil-detuvo-a-un-ladron-en-bicicleta\/","title":{"rendered":"POLICIALES EN LIBRES: ROBARON UNA MOTO TIT\u00c1N DEL HALL DE UNA CASA Y UN POLIC\u00cdA DE CIVIL DETUVO A UN LADR\u00d3N EN BICICLETA"},"content":{"rendered":"<p><strong>Policiales\u00a0<\/strong><\/p>\n<p>Paso de los Libres Corrientes<\/p>\n<p>2 de mayo de 2026<\/p>\n<p><strong>Se confiaron y le llevaron la moto<\/strong><\/p>\n<p>Alejandro Rol\u00f3n, de 19 a\u00f1os y domiciliado en 5ta Secci\u00f3n Palmar, denunci\u00f3 el robo de su motocicleta. El joven fue hasta la casa de su novia, ubicada \u201ca dos cuadras de Kari Modas\u201d, y dej\u00f3 el rodado en el hall de la vivienda.<\/p>\n<p>\u201cPor confianza, porque estaba dentro de la casa, dej\u00f3 la llave\u201d, se\u00f1alaron fuentes policiales. Cuando sali\u00f3 a las 00:30, la moto ya no estaba.<\/p>\n<p>El veh\u00edculo sustra\u00eddo es una Honda Tit\u00e1n 150 c.c., color roja.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Polic\u00eda de franco lo corri\u00f3 en bici y lo detuvo<\/strong><\/p>\n<p>El otro hecho ocurri\u00f3 ayer a las 19:30. Un llamado al 911 alert\u00f3 sobre un robo en avenida Jorge Newbery.<\/p>\n<p>El sargento G\u00f3mez, de la Polic\u00eda Rural e Inspecci\u00f3n General, que estaba de franco y vestido de civil, circulaba en bicicleta cuando vio que un hombre le arrebataba la cartera a una mujer.<\/p>\n<p>\u201cLe da la voz de alto, no le hacen caso, salen a disparar. \u00c9l lo sigue en la bicicleta hasta que lo reduce\u201d, detallaron.<\/p>\n<p>El ladr\u00f3n fue identificado como Juan Ver\u00f3n, de 42 a\u00f1os, del barrio Joaqu\u00edn Madariaga. Fue alcanzado en Jorge Newbery, cerca de la Ruta Nacional 117.<\/p>\n<p>La v\u00edctima es Romero Celia, tambi\u00e9n del barrio Palmar. Al llegar el m\u00f3vil policial, se comprob\u00f3 que Ver\u00f3n ten\u00eda en su poder un cuchillo artesanal de 22 cent\u00edmetros y una varilla con punta de m\u00e1s de 30 cent\u00edmetros. Qued\u00f3 detenido.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Policiales\u00a0 Paso de los Libres Corrientes 2 de mayo de 2026 Se confiaron y le llevaron la moto Alejandro Rol\u00f3n, de 19 a\u00f1os y domiciliado en 5ta Secci\u00f3n Palmar, denunci\u00f3 el robo de su motocicleta. El joven fue hasta la casa de su novia, ubicada \u201ca dos cuadras de Kari Modas\u201d, y dej\u00f3 el rodado [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":9485,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[77],"tags":[],"class_list":["post-9484","post","type-post","status-publish","format-standard","has-post-thumbnail","category-paso-de-los-libres"],"_links":{"self":[{"href":"https:\/\/elpueblonoticia.com.ar\/web\/wp-json\/wp\/v2\/posts\/9484","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elpueblonoticia.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elpueblonoticia.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elpueblonoticia.com.ar\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/elpueblonoticia.com.ar\/web\/wp-json\/wp\/v2\/comments?post=9484"}],"version-history":[{"count":0,"href":"https:\/\/elpueblonoticia.com.ar\/web\/wp-json\/wp\/v2\/posts\/9484\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elpueblonoticia.com.ar\/web\/wp-json\/wp\/v2\/media\/9485"}],"wp:attachment":[{"href":"https:\/\/elpueblonoticia.com.ar\/web\/wp-json\/wp\/v2\/media?parent=9484"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elpueblonoticia.com.ar\/web\/wp-json\/wp\/v2\/categories?post=9484"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elpueblonoticia.com.ar\/web\/wp-json\/wp\/v2\/tags?post=9484"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}