{"id":9479,"date":"2026-05-05T09:50:37","date_gmt":"2026-05-05T12:50:37","guid":{"rendered":"https:\/\/elpueblonoticia.com.ar\/web\/?p=9479"},"modified":"2026-05-05T09:50:37","modified_gmt":"2026-05-05T12:50:37","slug":"empleados-judiciales-refuerzan-el-pedido-del-6-por-ciento-de-aumento","status":"publish","type":"post","link":"https:\/\/elpueblonoticia.com.ar\/web\/2026\/05\/05\/empleados-judiciales-refuerzan-el-pedido-del-6-por-ciento-de-aumento\/","title":{"rendered":"Empleados judiciales refuerzan el pedido del 6 por ciento de aumento"},"content":{"rendered":"<div id=\"modalIntrotext\">\n<div><img loading=\"lazy\" decoding=\"async\" id=\"media-1\" class=\"\" src=\"https:\/\/www.diarioepoca.com\/content\/bucket\/9\/1487149w380h264c.jpg.webp\" alt=\"\" width=\"869\" height=\"604\" \/><\/div>\n<div>Los dos sindicatos del sector estar\u00e1n hoy en las calles para solicitar una pronta soluci\u00f3n a la incertidumbre que se presenta el pago correspondiente al mes de abril. Hoy estar\u00e1 presente Julio Piumato, titular de la Uni\u00f3n de Empleados de la Justicia de la Naci\u00f3n.<\/div>\n<div><\/div>\n<div>\n<div>Pese a la reuni\u00f3n que mantuvo ayer el gobernador de la provincia, Juan Pablo Vald\u00e9s, con miembros del Superior Tribunal de Justicia, los trabajadores judiciales de Corrientes solicitan pronta soluci\u00f3n al aumento del 6 por ciento otorgado por acordada de los ministros del STJ.<\/div>\n<div>\n<div><\/div>\n<div>En el caso de los trabajadores nucleados en la Uni\u00f3n de Empleados de la Justicia de la Naci\u00f3n (UEJN) seccional 11 Corrientes, volver\u00e1n a manifestarse hoy por el pedido de incremento salarial.<\/div>\n<div>La concentraci\u00f3n de este sector desde la 10:50 en la plaza Seca que se encuentra en el edificio judicial de la calle 9 de Julio y San Juan.<\/div>\n<\/div>\n<div>\n<div><\/div>\n<div>Los organizadores informaron a \u00e9poca que la marcha estar\u00e1 encabezada por Julio Piumato \u0096m\u00e1ximo referente del UEJN-.<\/div>\n<\/div>\n<div>\n<div><\/div>\n<div>Con la consigna, &#8220;Los trabajadores judiciales federales y provinciales nos convocamos en defensa de la independencia judicial, la autonom\u00eda financiera, la recomposici\u00f3n de nuestros salarios y en contra de los violencia laboral ejercida por la jueza Pozzer Penzo&#8221;, los miembros de este gremio se har\u00e1n sentir nuevamente en las calles del centro capitalino.<\/div>\n<\/div>\n<div>\n<div><\/div>\n<div>De acuerdo a lo programado, la marcha pasar\u00e1 por el edificio del Superior Tribunal de Justicia (STJ) y concluir\u00e1 en la plaza 25 de Mayo. &#8220;Los derechos no se piden, se defienden&#8221;, se exhibe en otros de los comunicados que emitieron.<\/div>\n<\/div>\n<div>\n<div><\/div>\n<div>De acuerdo a los datos a los que pudo acceder este medio, hoy estar\u00e1n presentes dirigentes de distintas provincias y localidades de Corrientes, entre las que se puede mencionar Chaco, Misiones, Entre R\u00edos, Formosa, Goya y Paso de los Libres. Todos integran el plantel de dirigentes que se desempe\u00f1an en la Justicia Federal.<\/div>\n<\/div>\n<div>\n<div><\/div>\n<div>Por la convocatoria antes del mediod\u00eda podr\u00eda cortarse el tr\u00e1nsito en calle La Rioja y Pellegrini, frente al edificio del STJ y luego en 25 de Mayo y Salta donde se cerrar\u00e1 la movilizaci\u00f3n con un discurso de Julio Piumato.<\/div>\n<h2 class=\"\">El SITRAJ pide definiciones<\/h2>\n<div>En un comunicado de prensa, el Sindicato de Trabajadores Judiciales (SITRAJ) afirma que sigue sin definirse c\u00f3mo se liquidar\u00e1 el 6% de recomposici\u00f3n salarial correspondiente al mes de abril y reiter\u00f3 que se encuentran en estado de alerta y asamblea permanente.<\/div>\n<\/div>\n<div>\n<div><\/div>\n<div>En esta instancia se definir\u00e1n los pasos a seguir. De no haber resoluci\u00f3n al pedido de la liquidaci\u00f3n del 6% no descartan intensificar los reclamos frente al Superior Tribunal de Justicia.<\/div>\n<div><\/div>\n<div>Adem\u00e1s aseguraron que pese a la reuni\u00f3n que mantuvieron ayer el Gobernador y los ministros del STJ, los empleados judiciales a\u00fan siguen esperando respuestas.<\/div>\n<\/div>\n<div>\n<div><\/div>\n<div>&#8220;Seguimos con los bolsillos m\u00e1s deteriorados y lejos del salario digno que reclamamos y en medio de una crisis institucional de gravedad surgida del quiebre de la divisi\u00f3n de poderes y de la indispensable independencia judicial&#8221;, se desprende del comunicado oficial del gremio.<\/div>\n<\/div>\n<div>\n<div><\/div>\n<div>En la parte final remarcan que desde el momento que el Poder Ejecutivo provincial a trav\u00e9s de su Ministro de Hacienda desconoci\u00f3 un acuerdo del STJ, se produjo un quiebre que debe frenarse. &#8220;Insistimos: que el STJ, cabeza de gobierno del Poder Judicial, cumpla y haga cumplir la constituci\u00f3n y las leyes. De pie o de rodillas es la opci\u00f3n de las m\u00e1ximas autoridades de la Justicia&#8221;.<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Los dos sindicatos del sector estar\u00e1n hoy en las calles para solicitar una pronta soluci\u00f3n a la incertidumbre que se presenta el pago correspondiente al mes de abril. Hoy estar\u00e1 presente Julio Piumato, titular de la Uni\u00f3n de Empleados de la Justicia de la Naci\u00f3n. Pese a la reuni\u00f3n que mantuvo ayer el gobernador de [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":9480,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[78],"tags":[],"class_list":["post-9479","post","type-post","status-publish","format-standard","has-post-thumbnail","category-generales"],"_links":{"self":[{"href":"https:\/\/elpueblonoticia.com.ar\/web\/wp-json\/wp\/v2\/posts\/9479","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elpueblonoticia.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elpueblonoticia.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elpueblonoticia.com.ar\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/elpueblonoticia.com.ar\/web\/wp-json\/wp\/v2\/comments?post=9479"}],"version-history":[{"count":0,"href":"https:\/\/elpueblonoticia.com.ar\/web\/wp-json\/wp\/v2\/posts\/9479\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elpueblonoticia.com.ar\/web\/wp-json\/wp\/v2\/media\/9480"}],"wp:attachment":[{"href":"https:\/\/elpueblonoticia.com.ar\/web\/wp-json\/wp\/v2\/media?parent=9479"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elpueblonoticia.com.ar\/web\/wp-json\/wp\/v2\/categories?post=9479"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elpueblonoticia.com.ar\/web\/wp-json\/wp\/v2\/tags?post=9479"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}