{"id":9472,"date":"2026-05-05T08:42:53","date_gmt":"2026-05-05T11:42:53","guid":{"rendered":"https:\/\/elpueblonoticia.com.ar\/web\/?p=9472"},"modified":"2026-05-05T08:42:53","modified_gmt":"2026-05-05T11:42:53","slug":"el-stj-confirmo-que-no-se-puede-exigir-el-pago-de-multas-para-renovar-la-licencia-de-conducir","status":"publish","type":"post","link":"https:\/\/elpueblonoticia.com.ar\/web\/2026\/05\/05\/el-stj-confirmo-que-no-se-puede-exigir-el-pago-de-multas-para-renovar-la-licencia-de-conducir\/","title":{"rendered":"El STJ confirm\u00f3 que no se puede exigir el pago de multas para renovar la licencia de conducir"},"content":{"rendered":"<p><strong>Judiciales<\/strong><\/p>\n<p>Martes 5 de Mayo de 2026<\/p>\n<p>El m\u00e1ximo tribunal provincial declar\u00f3 inadmisible el recurso de la Municipalidad de Paso de los Libres y ratific\u00f3 que condicionar la renovaci\u00f3n del carnet al pago previo de infracciones carece de sustento legal y vulnera derechos constitucionales.<\/p>\n<p>El Superior Tribunal de Justicia de Corrientes resolvi\u00f3 en la Sentencia N\u00b0 315 un amparo iniciado contra la Municipalidad de Paso de los Libres, que exig\u00eda a un vecino abonar multas de tr\u00e1nsito como condici\u00f3n para renovar su licencia de conducir.<\/p>\n<p>El Tribunal confirm\u00f3 lo decidido en instancias anteriores y sostuvo que esa exigencia no est\u00e1 prevista en la legislaci\u00f3n vigente, por lo que constituye una restricci\u00f3n ileg\u00edtima al derecho de circular.<\/p>\n<p>En su an\u00e1lisis, los ministros remarcaron que la Ley Nacional de Tr\u00e1nsito s\u00f3lo exige verificar antecedentes e inhabilitaciones, pero no autoriza a impedir la renovaci\u00f3n por deudas econ\u00f3micas.<\/p>\n<p>Adem\u00e1s, se\u00f1alaron que la medida municipal desnaturaliza la finalidad de la normativa de tr\u00e1nsito y la transforma en un mecanismo recaudatorio, vulnerando principios constitucionales como la legalidad, la razonabilidad y la libertad de circulaci\u00f3n.<\/p>\n<p>Por unanimidad, el Superior Tribunal de Justicia resolvi\u00f3: Declarar inadmisible el recurso extraordinario de la Municipalidad. De este modo, qued\u00f3 firme el criterio de que no se puede impedir la renovaci\u00f3n de la licencia de conducir por la existencia de multas impagas, si esa exigencia no est\u00e1 prevista por la ley.<\/p>\n<p>Resoluci\u00f3n del STJ<\/p>\n<p>El ministro del STJ, doctor Luis Eduardo Rey V\u00e1zquez, sostuvo en su voto que el recurso de la Municipalidad no cumpl\u00eda con los requisitos t\u00e9cnicos exigidos y no lograba refutar el argumento central del fallo anterior.<\/p>\n<p>\u201cEl recurrente no logr\u00f3 refutar el argumento central de la C\u00e1mara, consistente en que la exigencia municipal de pago previo de multas carec\u00eda de sustento normativo en la legislaci\u00f3n aplicable\u201d, sostuvo.<\/p>\n<p>Adem\u00e1s, remarc\u00f3 que el requisito impuesto por el municipio es contrario al principio de legalidad: \u201cLa exigencia resulta violatoria del art. 19 de la CN, en cuanto nadie puede ser obligado a hacer lo que la ley no manda.\u201d<\/p>\n<p>Tambi\u00e9n destac\u00f3 que el amparo era la v\u00eda adecuada para proteger el derecho afectado.<\/p>\n<p>El ministro, doctor Alejandro Alberto Chain, adhiri\u00f3 al voto del primer votante en todos sus t\u00e9rminos por compartir sus fundamentos. El ministro, doctor Eduardo Panseri coincidi\u00f3 con la soluci\u00f3n propuesta. Por su parte, el ministro doctor Fernando Augusto Niz tambi\u00e9n acompa\u00f1\u00f3 el voto principal y el doctor Guillermo Horacio Semhan se sum\u00f3 al criterio del tribunal.<\/p>\n<p>Fuente: Ignacio Villanueva<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Judiciales Martes 5 de Mayo de 2026 El m\u00e1ximo tribunal provincial declar\u00f3 inadmisible el recurso de la Municipalidad de Paso de los Libres y ratific\u00f3 que condicionar la renovaci\u00f3n del carnet al pago previo de infracciones carece de sustento legal y vulnera derechos constitucionales. El Superior Tribunal de Justicia de Corrientes resolvi\u00f3 en la Sentencia [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":9473,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[85],"tags":[],"class_list":["post-9472","post","type-post","status-publish","format-standard","has-post-thumbnail","category-judiciales"],"_links":{"self":[{"href":"https:\/\/elpueblonoticia.com.ar\/web\/wp-json\/wp\/v2\/posts\/9472","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elpueblonoticia.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elpueblonoticia.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elpueblonoticia.com.ar\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/elpueblonoticia.com.ar\/web\/wp-json\/wp\/v2\/comments?post=9472"}],"version-history":[{"count":0,"href":"https:\/\/elpueblonoticia.com.ar\/web\/wp-json\/wp\/v2\/posts\/9472\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elpueblonoticia.com.ar\/web\/wp-json\/wp\/v2\/media\/9473"}],"wp:attachment":[{"href":"https:\/\/elpueblonoticia.com.ar\/web\/wp-json\/wp\/v2\/media?parent=9472"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elpueblonoticia.com.ar\/web\/wp-json\/wp\/v2\/categories?post=9472"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elpueblonoticia.com.ar\/web\/wp-json\/wp\/v2\/tags?post=9472"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}