{"id":8345,"date":"2026-03-31T12:31:41","date_gmt":"2026-03-31T15:31:41","guid":{"rendered":"https:\/\/elpueblonoticia.com.ar\/web\/?p=8345"},"modified":"2026-03-31T12:31:41","modified_gmt":"2026-03-31T15:31:41","slug":"argentina-vs-zambia-por-un-amistoso-internacional-horario-formaciones-y-tv","status":"publish","type":"post","link":"https:\/\/elpueblonoticia.com.ar\/web\/2026\/03\/31\/argentina-vs-zambia-por-un-amistoso-internacional-horario-formaciones-y-tv\/","title":{"rendered":"Argentina vs. Zambia, por un amistoso internacional: horario, formaciones y tv"},"content":{"rendered":"<p>La Albiceleste se medir\u00e1 el martes desde las 20.15 con el conjunto africano por el segundo amistoso de la Fecha FIFA, en lo que ser\u00e1 la despedida del plantel antes de la Copa del Mundo.<\/p>\n<p>Argentina enfrentar\u00e1 a\u00a0Zambia\u00a0este martes desde las 20.15 en La Bombonera, en lo que ser\u00e1 el cierre de la doble fecha FIFA de marzo y una de las \u00faltimas pruebas antes del Mundial de Canad\u00e1, M\u00e9xico y Estados Unidos 2026.<\/p>\n<section class=\"detail-body second-paragraph\">\n<section class=\"body-content note-body content-protected-false\">\n<p data-start=\"844\" data-end=\"1218\">El equipo dirigido por Lionel Scaloni viene de vencer 2 a 1 a Mauritania con goles de Enzo Fern\u00e1ndez y Nico Paz, aunque el funcionamiento dej\u00f3 algunas dudas en relaci\u00f3n al nivel colectivo. En ese contexto, el cuerpo t\u00e9cnico aprovechar\u00e1 este compromiso para seguir evaluando variantes y consolidar el recambio generacional que comenz\u00f3 a tomar forma en los \u00faltimos encuentros.<\/p>\n<section class=\"detail-body\">\n<section class=\"body-content note-body content-protected-false\">\n<p data-start=\"1220\" data-end=\"1520\">Adem\u00e1s, el amistoso representa una oportunidad clave para varios futbolistas que buscan asegurarse un lugar en la lista definitiva para la Copa del Mundo. Entre los nombres que podr\u00edan sumar minutos aparecen Gianluca Prestianni y Franco Mastantuono, dos j\u00f3venes que vienen siendo observados de cerca.<\/p>\n<\/section>\n<\/section>\n<section class=\"detail-body\">\n<section class=\"body-content note-body content-protected-false\">\n<p data-start=\"1767\" data-end=\"2067\">El seleccionado africano, conocido como los \u201cChipolopolo\u201d, afronta el compromiso como una buena medida frente a uno de los equipos m\u00e1s fuertes del mundo. El conjunto dirigido por George Lwandamina no logr\u00f3 clasificarse al Mundial 2026 tras finalizar cuarto en su grupo de las Eliminatorias de la CAF. A pesar de no haber alcanzado el objetivo, cuenta con futbolistas de experiencia internacional como Patson Daka y Fashion Sakala, quienes lideran un ataque veloz que intentar\u00e1 aprovechar los espacios que pueda generar el partido.<\/p>\n<\/section>\n<\/section>\n<section class=\"detail-body\">\n<section class=\"body-content note-body content-protected-false\">\n<p data-start=\"2307\" data-end=\"2537\" data-is-last-node=\"\" data-is-only-node=\"\">El duelo servir\u00e1 como despedida del plantel argentino antes de la lista final para la Copa del Mundo, en un contexto en el que el cuerpo t\u00e9cnico busca llegar con el mayor rodaje posible para sostener el protagonismo internacional.<\/p>\n<h2><strong>Probables formaciones del encuentro entre la Selecci\u00f3n Argentina y Zambia<\/strong><\/h2>\n<ul>\n<li><strong>Argentina<\/strong>: Ger\u00f3nimo Rulli; Agust\u00edn Giay, Lucas Mart\u00ednez Quarta, Nicol\u00e1s Otamendi, Nicol\u00e1s Tagliafico; Exequiel Palacios, Leandro Paredes, Valent\u00edn Barco; Gianluca Prestianni, Jos\u00e9 Manuel L\u00f3pez y Lionel Messi. DT: Lionel Scaloni.<\/li>\n<li><strong>Zambia<\/strong>: Lawrence Mwansa; Benedict Banda, Frankie Musonda, Stoppila Sunzu, Dominic Chanda; Kelvin Kapumbu, Emmanuel Banda; Fashion Sakala, Kings Kangwa, Lameck Banda; Patson Daka. DT: George Lwandamina.<\/li>\n<\/ul>\n<h2><strong>Otros datos del partido entre la Selecci\u00f3n Argentina y Zambia<\/strong><\/h2>\n<ul>\n<li>Horario: 20.15<\/li>\n<li>Estadio: La Bombonera<\/li>\n<li>TV: DSports y Telef\u00e9<\/li>\n<\/ul>\n<\/section>\n<\/section>\n<\/section>\n<\/section>\n","protected":false},"excerpt":{"rendered":"<p>La Albiceleste se medir\u00e1 el martes desde las 20.15 con el conjunto africano por el segundo amistoso de la Fecha FIFA, en lo que ser\u00e1 la despedida del plantel antes de la Copa del Mundo. Argentina enfrentar\u00e1 a\u00a0Zambia\u00a0este martes desde las 20.15 en La Bombonera, en lo que ser\u00e1 el cierre de la doble fecha [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":8346,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-8345","post","type-post","status-publish","format-standard","has-post-thumbnail","category-deportes"],"_links":{"self":[{"href":"https:\/\/elpueblonoticia.com.ar\/web\/wp-json\/wp\/v2\/posts\/8345","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elpueblonoticia.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elpueblonoticia.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elpueblonoticia.com.ar\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/elpueblonoticia.com.ar\/web\/wp-json\/wp\/v2\/comments?post=8345"}],"version-history":[{"count":0,"href":"https:\/\/elpueblonoticia.com.ar\/web\/wp-json\/wp\/v2\/posts\/8345\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elpueblonoticia.com.ar\/web\/wp-json\/wp\/v2\/media\/8346"}],"wp:attachment":[{"href":"https:\/\/elpueblonoticia.com.ar\/web\/wp-json\/wp\/v2\/media?parent=8345"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elpueblonoticia.com.ar\/web\/wp-json\/wp\/v2\/categories?post=8345"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elpueblonoticia.com.ar\/web\/wp-json\/wp\/v2\/tags?post=8345"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}