{"id":12453,"date":"2026-07-13T22:18:28","date_gmt":"2026-07-14T01:18:28","guid":{"rendered":"https:\/\/elpueblonoticia.com.ar\/web\/?p=12453"},"modified":"2026-07-13T22:19:46","modified_gmt":"2026-07-14T01:19:46","slug":"solicitan-la-reapertura-del-parque-nacional-ibera-tras-casi-dos-meses-de-cierre-por-la-presencia-de-un-yaguarete","status":"publish","type":"post","link":"https:\/\/elpueblonoticia.com.ar\/web\/2026\/07\/13\/solicitan-la-reapertura-del-parque-nacional-ibera-tras-casi-dos-meses-de-cierre-por-la-presencia-de-un-yaguarete\/","title":{"rendered":"Solicitan la reapertura del Parque Nacional Iber\u00e1 tras casi dos meses de cierre por la presencia de un yaguaret\u00e9"},"content":{"rendered":"<p>La C\u00e1mara de Turismo del Iber\u00e1 y la Asociaci\u00f3n de Gu\u00edas de Colonia Carlos Pellegrini pidieron a la Administraci\u00f3n de Parques Nacionales (APN) que reconsidere el cierre del Parque Nacional Iber\u00e1, dispuesto hace casi dos meses debido a la presencia del yaguaret\u00e9 Omb\u00fa, y propusieron implementar protocolos de seguridad para permitir nuevamente el ingreso de visitantes.<\/p>\n<p>El planteo fue realizado mediante una nota enviada al presidente del Directorio de la APN, Sergio Mart\u00edn \u00c1lvarez, firmada por Estrella Losada, titular de la C\u00e1mara de Turismo del Iber\u00e1, y Gast\u00f3n Bocalandro, representante de la Asociaci\u00f3n de Gu\u00edas de Pellegrini.<\/p>\n<p>En el documento, las entidades se\u00f1alaron que el sector de uso p\u00fablico permaneci\u00f3 cerrado durante gran parte de este per\u00edodo y lamentaron que, pese a haber solicitado alternativas para reabrir el parque de manera segura, a\u00fan no recibieron una respuesta oficial.<\/p>\n<p>Tambi\u00e9n manifestaron que no se brindaron capacitaciones ni se difundieron protocolos de actuaci\u00f3n para gu\u00edas y prestadores tur\u00edsticos frente a posibles avistamientos del yaguaret\u00e9. En contraste, destacaron que la Direcci\u00f3n de Parques y Reservas de Corrientes s\u00ed llev\u00f3 adelante acciones de capacitaci\u00f3n sobre este tema.<\/p>\n<p>Los representantes del sector recordaron que uno de los principales objetivos del programa de reintroducci\u00f3n del yaguaret\u00e9, impulsado por Fundaci\u00f3n Rewilding Argentina, el Gobierno provincial y la APN, fue fortalecer el turismo de naturaleza mediante la presencia de esta especie emblem\u00e1tica. Por ello, consideraron que los encuentros con ejemplares en libertad ser\u00e1n cada vez m\u00e1s frecuentes y que la respuesta no deber\u00eda ser el cierre del parque.<\/p>\n<p>Como alternativa, propusieron habilitar recorridos por caminos ya existentes, establecer protocolos espec\u00edficos para actuar ante avistamientos y aplicar medidas similares a las que ya funcionan en otras \u00e1reas protegidas del pa\u00eds y de la regi\u00f3n, donde conviven visitantes y grandes felinos.<\/p>\n<p>Finalmente, expresaron su disposici\u00f3n a trabajar en conjunto con la Administraci\u00f3n de Parques Nacionales para encontrar una soluci\u00f3n que permita proteger al yaguaret\u00e9 sin afectar el desarrollo de la actividad tur\u00edstica en la regi\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La C\u00e1mara de Turismo del Iber\u00e1 y la Asociaci\u00f3n de Gu\u00edas de Colonia Carlos Pellegrini pidieron a la Administraci\u00f3n de Parques Nacionales (APN) que reconsidere el cierre del Parque Nacional Iber\u00e1, dispuesto hace casi dos meses debido a la presencia del yaguaret\u00e9 Omb\u00fa, y propusieron implementar protocolos de seguridad para permitir nuevamente el ingreso de [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":12458,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[78],"tags":[],"class_list":["post-12453","post","type-post","status-publish","format-standard","has-post-thumbnail","category-generales"],"_links":{"self":[{"href":"https:\/\/elpueblonoticia.com.ar\/web\/wp-json\/wp\/v2\/posts\/12453","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elpueblonoticia.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elpueblonoticia.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elpueblonoticia.com.ar\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/elpueblonoticia.com.ar\/web\/wp-json\/wp\/v2\/comments?post=12453"}],"version-history":[{"count":1,"href":"https:\/\/elpueblonoticia.com.ar\/web\/wp-json\/wp\/v2\/posts\/12453\/revisions"}],"predecessor-version":[{"id":12455,"href":"https:\/\/elpueblonoticia.com.ar\/web\/wp-json\/wp\/v2\/posts\/12453\/revisions\/12455"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elpueblonoticia.com.ar\/web\/wp-json\/wp\/v2\/media\/12458"}],"wp:attachment":[{"href":"https:\/\/elpueblonoticia.com.ar\/web\/wp-json\/wp\/v2\/media?parent=12453"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elpueblonoticia.com.ar\/web\/wp-json\/wp\/v2\/categories?post=12453"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elpueblonoticia.com.ar\/web\/wp-json\/wp\/v2\/tags?post=12453"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}