{"id":12316,"date":"2026-07-10T19:09:43","date_gmt":"2026-07-10T22:09:43","guid":{"rendered":"https:\/\/elpueblonoticia.com.ar\/web\/?p=12316"},"modified":"2026-07-10T19:09:43","modified_gmt":"2026-07-10T22:09:43","slug":"mariano-hormaechea-destaco-el-crecimiento-de-goya-y-los-desafios-de-la-gestion","status":"publish","type":"post","link":"https:\/\/elpueblonoticia.com.ar\/web\/2026\/07\/10\/mariano-hormaechea-destaco-el-crecimiento-de-goya-y-los-desafios-de-la-gestion\/","title":{"rendered":"Mariano Hormaechea destac\u00f3 el crecimiento de Goya y los desaf\u00edos de la gesti\u00f3n"},"content":{"rendered":"<p>En el marco de una intensa agenda institucional por el D\u00eda de la Independencia Argentina, el intendente de Goya, doctor Mariano Hormaechea, particip\u00f3 del streaming oficial de la 8\u00b0 Edici\u00f3n de la Feria del Libro durante su quinta jornada, donde repas\u00f3 actividades, proyectos de gesti\u00f3n y el presente de la ciudad, destacando especialmente el crecimiento sostenido del evento cultural.<\/p>\n<p>\u201cMuy contento despu\u00e9s de una jornada larga para m\u00ed, alegr\u00eda por estar en esta 8\u00b0 Edici\u00f3n de nuestra feria del libro que viene creciendo a\u00f1o a a\u00f1o\u201d, comenz\u00f3 se\u00f1alando el jefe comunal, tras haber encabezado el acto en Goya por el 9 de julio.<\/p>\n<p>El intendente doctor Mariano Hormaechea detall\u00f3 su participaci\u00f3n en los actos centrales desarrollados en Corrientes: \u201cArrancamos temprano, primero tuvimos el izamiento de la bandera en Corrientes Capital, despu\u00e9s fuimos al tedeum, luego al desfile realizado en la Costanera Correntina, tras la convocatoria realizada por el gobernador de la Provincia Juan Pablo Vald\u00e9s\u201d.<\/p>\n<p>En ese sentido, explic\u00f3 la reorganizaci\u00f3n del tradicional desfile local: \u201cTambi\u00e9n estuvo convocado el Batall\u00f3n de Ingenieros de Monte 12 de Goya\u2026 Todos los 9 de julio realizamos nuestro desfile tradicional donde participa toda la ciudad y en esta oportunidad\u2026 decidimos luego un acto m\u00e1s chico en Goya a la tarde y lo pasamos todo para el 9 de noviembre\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>CONVOCATORIA PARA EL 9 DE NOVIEMBRE<\/p>\n<p>Sobre esta nueva fecha, el intendente precis\u00f3: \u201cEl 9 de noviembre vamos a convocar a toda la ciudadan\u00eda al celebrarse el cumplea\u00f1os de la ciudad\u201d. Y agreg\u00f3: \u201ccomo nosotros no ten\u00edamos fecha de fundaci\u00f3n, en Rosario pasaba lo mismo, a trav\u00e9s de una ley provincial\u2026 El 9 de noviembre es la fecha de la Primera Radicaci\u00f3n de Goya como ciudad\u201d.<\/p>\n<p>Asimismo, indic\u00f3 que esta celebraci\u00f3n se enmarca dentro de un calendario m\u00e1s amplio: \u201cLo tomamos, el a\u00f1o pasado lo llevamos a la pr\u00e1ctica\u2026 arranca el 7 de octubre con la Patrona Nuestra Se\u00f1ora del Rosario y terminamos celebrando el 9 de noviembre\u2026 la idea es que el 9 de noviembre festejemos el cumplea\u00f1os y convocaremos a toda la comunidad para realizar el desfile\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>GESTI\u00d3N MUNICIPAL Y PROYECTOS ESTRAT\u00c9GICOS<\/p>\n<p>En cuanto a la gesti\u00f3n municipal, Hormaechea remarc\u00f3 la continuidad de obras y proyectos estrat\u00e9gicos: \u201cGoya tiene muchas l\u00edneas de trabajo, que lo planteamos mirando hacia adelante\u201d. Entre los desaf\u00edos mencion\u00f3: \u201cseguir trabajando para en alg\u00fan momento traer alguna Universidad P\u00fablica a la ciudad\u201d y \u201cretomar la Balsa que nos une con Reconquista y Avellaneda \u2013Santa Fe\u2013\u201d.<\/p>\n<p>En un contexto econ\u00f3mico complejo, el intendente explic\u00f3 que se analizan herramientas de inversi\u00f3n: \u201cEstamos mirando el contexto internacional\u2026 a trav\u00e9s de distintas herramientas como el RIGI (R\u00e9gimen de Incentivo para Grandes Inversiones) o el s\u00faper RIGI\u201d. En ese marco, destac\u00f3 un proyecto clave de infraestructura: \u201cHoy lo que queremos es presentar nuestro proyecto ejecutivo\u2026 para ese famoso puente que ansiamos tanto los goyanos\u201d.<\/p>\n<p>Sobre esta iniciativa, ampli\u00f3: \u201cNosotros tenemos ejecutivo de un puente que nos va a unir a las dos provincias\u2026 es el \u00fanico puente que tiene un proyecto y no as\u00ed Resistencia\/Corrientes o Paran\u00e1\/Santa Fe\u2026 creemos que hay una gran oportunidad de visibilizar y hacer que un capital extranjero se interese\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>LA FERIA DEL LIBRO COMO POL\u00cdTICA CULTURAL<\/p>\n<p>Respecto a la Feria del Libro, el jefe comunal valor\u00f3 la decisi\u00f3n de sostener el evento pese a las dificultades: \u201cEsta 8\u00b0 edici\u00f3n no quer\u00edamos dejarla pasar\u2026 logramos el objetivo de poder inaugurarla, hacer una feria que est\u00e1 a la altura de las anteriores, con una convocatoria importante de escritores, periodistas, artistas\u201d.<\/p>\n<p>Tambi\u00e9n destac\u00f3 el enfoque educativo: \u201cla oportunidad para nuestras escuelas\u2026 se comenz\u00f3 la semana previa al comienzo de las vacaciones de invierno\u201d. Y subray\u00f3 el acompa\u00f1amiento a autores regionales: \u201cla idea de la Feria no es solamente mostrar lo de Goya sino dar estos espacios\u2026 para otros escritores o artistas de la zona\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>MARCA CIUDAD Y DESARROLLO TUR\u00cdSTICO<\/p>\n<p>En relaci\u00f3n al desarrollo tur\u00edstico, record\u00f3 el reciente relanzamiento de la marca ciudad: \u201cLo que hicimos es relanzar nuestra marca con este nuevo slogan que es Goya Energ\u00eda Natural\u2026 creemos que el turismo tiene un gran potencial\u201d. En ese sentido, se\u00f1al\u00f3 el trabajo con consultoras de Villa Elisa y compar\u00f3: \u201ccomo nosotros con casi 100.000 habitantes no vamos a poder ir por ese camino\u2026 tenemos recursos como la Reserva Natural Isor\u00f3, la Fiesta Nacional del Surub\u00ed, la Feria del Libro\u201d.<\/p>\n<p>\u201cEstamos buscando que Goya sea todo el a\u00f1o\u2026 no solamente en la Fiesta del Surub\u00ed que es nuestra gran vidriera, sino durante todo el a\u00f1o\u201d, afirm\u00f3.<\/p>\n<p>&nbsp;<\/p>\n<p>CIERRE DE LA FERIA Y PROYECTO HIST\u00d3RICO<\/p>\n<p>En el cierre de la feria, este domingo, el intendente anticip\u00f3 una actividad destacada junto al historiador Felipe Pigna: \u201cvamos a estar haciendo el cierre\u2026 presentando un tr\u00e1iler y contar todo el trabajo\u2026 por el libro de la historia oficial de Goya\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>F\u00daTBOL, SELECCI\u00d3N Y CELEBRACIONES POPULARES<\/p>\n<p>Antes de finalizar, tambi\u00e9n hubo lugar para el f\u00fatbol y la actualidad de la selecci\u00f3n argentina: \u201cestamos sufriendo, con las c\u00e1balas\u2026 esta selecci\u00f3n deja mensajes muy lindos\u201d. Sobre los festejos locales, indic\u00f3: \u201chist\u00f3ricamente es una costumbre festejar en la plaza Mitre\u2026 me sorprendi\u00f3 porque cada triunfo fue un festejo\u201d.<\/p>\n<p>INVITACI\u00d3N A LA COMUNIDAD<\/p>\n<p>Finalmente, Hormaechea extendi\u00f3 la invitaci\u00f3n a la comunidad: \u201cV\u00e9nganse todos a disfrutar de la Feria del Libro de Goya que vamos a estar hasta este domingo 12\u201d, concluy\u00f3.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En el marco de una intensa agenda institucional por el D\u00eda de la Independencia Argentina, el intendente de Goya, doctor Mariano Hormaechea, particip\u00f3 del streaming oficial de la 8\u00b0 Edici\u00f3n de la Feria del Libro durante su quinta jornada, donde repas\u00f3 actividades, proyectos de gesti\u00f3n y el presente de la ciudad, destacando especialmente el crecimiento [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":12317,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[56],"tags":[],"class_list":["post-12316","post","type-post","status-publish","format-standard","has-post-thumbnail","category-locales"],"_links":{"self":[{"href":"https:\/\/elpueblonoticia.com.ar\/web\/wp-json\/wp\/v2\/posts\/12316","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elpueblonoticia.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elpueblonoticia.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elpueblonoticia.com.ar\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/elpueblonoticia.com.ar\/web\/wp-json\/wp\/v2\/comments?post=12316"}],"version-history":[{"count":1,"href":"https:\/\/elpueblonoticia.com.ar\/web\/wp-json\/wp\/v2\/posts\/12316\/revisions"}],"predecessor-version":[{"id":12318,"href":"https:\/\/elpueblonoticia.com.ar\/web\/wp-json\/wp\/v2\/posts\/12316\/revisions\/12318"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elpueblonoticia.com.ar\/web\/wp-json\/wp\/v2\/media\/12317"}],"wp:attachment":[{"href":"https:\/\/elpueblonoticia.com.ar\/web\/wp-json\/wp\/v2\/media?parent=12316"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elpueblonoticia.com.ar\/web\/wp-json\/wp\/v2\/categories?post=12316"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elpueblonoticia.com.ar\/web\/wp-json\/wp\/v2\/tags?post=12316"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}