{"id":11805,"date":"2026-06-29T09:33:16","date_gmt":"2026-06-29T12:33:16","guid":{"rendered":"https:\/\/elpueblonoticia.com.ar\/web\/?p=11805"},"modified":"2026-06-29T09:37:36","modified_gmt":"2026-06-29T12:37:36","slug":"el-papa-leon-xiv-pidio-apoyo-internacional-para-venezuela-y-envio-una-ayuda-economica","status":"publish","type":"post","link":"https:\/\/elpueblonoticia.com.ar\/web\/2026\/06\/29\/el-papa-leon-xiv-pidio-apoyo-internacional-para-venezuela-y-envio-una-ayuda-economica\/","title":{"rendered":"El papa Le\u00f3n XIV pidi\u00f3 apoyo internacional para Venezuela y envi\u00f3 una ayuda econ\u00f3mica"},"content":{"rendered":"<p class=\"isSelectedEnd\">El papa Le\u00f3n XIV expres\u00f3 su solidaridad con el pueblo venezolano tras el fuerte terremoto que afect\u00f3 al pa\u00eds el pasado 24 de junio y anunci\u00f3 el env\u00edo de una asistencia inicial de 100.000 euros a trav\u00e9s de la Limosner\u00eda Apost\u00f3lica para colaborar con los damnificados.<\/p>\n<p class=\"isSelectedEnd\">Durante el rezo del \u00c1ngelus, el Sumo Pont\u00edfice manifest\u00f3 su cercan\u00eda con las familias afectadas, record\u00f3 a las v\u00edctimas fatales y elev\u00f3 oraciones por los heridos. Adem\u00e1s, agradeci\u00f3 el trabajo de los equipos de rescate y pidi\u00f3 que la comunidad internacional mantenga su apoyo al pueblo venezolano frente a la emergencia.<\/p>\n<p class=\"isSelectedEnd\">La ayuda fue coordinada por el Vaticano junto al nuncio apost\u00f3lico en Venezuela y autoridades de la Iglesia local, con el objetivo de responder a las necesidades m\u00e1s urgentes de las zonas afectadas.<\/p>\n<p class=\"isSelectedEnd\">En el marco del Consistorio extraordinario, Le\u00f3n XIV volvi\u00f3 a expresar su respaldo a Venezuela y, junto al Colegio Cardenalicio, reiter\u00f3 el llamado a la solidaridad internacional, al tiempo que pidi\u00f3 oraciones por las v\u00edctimas, sus familias y quienes participan en las tareas de asistencia.<\/p>\n<p>Por su parte, la Conferencia Episcopal Venezolana convoc\u00f3 a una jornada especial de oraci\u00f3n por los damnificados y las regiones afectadas, mientras que los obispos manifestaron su acompa\u00f1amiento espiritual y su deseo de que las comunidades encuentren consuelo y esperanza ante la tragedia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El papa Le\u00f3n XIV expres\u00f3 su solidaridad con el pueblo venezolano tras el fuerte terremoto que afect\u00f3 al pa\u00eds el pasado 24 de junio y anunci\u00f3 el env\u00edo de una asistencia inicial de 100.000 euros a trav\u00e9s de la Limosner\u00eda Apost\u00f3lica para colaborar con los damnificados. Durante el rezo del \u00c1ngelus, el Sumo Pont\u00edfice manifest\u00f3 [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":11810,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[81],"tags":[],"class_list":["post-11805","post","type-post","status-publish","format-standard","has-post-thumbnail","category-internacionales"],"_links":{"self":[{"href":"https:\/\/elpueblonoticia.com.ar\/web\/wp-json\/wp\/v2\/posts\/11805","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elpueblonoticia.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elpueblonoticia.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elpueblonoticia.com.ar\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/elpueblonoticia.com.ar\/web\/wp-json\/wp\/v2\/comments?post=11805"}],"version-history":[{"count":0,"href":"https:\/\/elpueblonoticia.com.ar\/web\/wp-json\/wp\/v2\/posts\/11805\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elpueblonoticia.com.ar\/web\/wp-json\/wp\/v2\/media\/11810"}],"wp:attachment":[{"href":"https:\/\/elpueblonoticia.com.ar\/web\/wp-json\/wp\/v2\/media?parent=11805"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elpueblonoticia.com.ar\/web\/wp-json\/wp\/v2\/categories?post=11805"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elpueblonoticia.com.ar\/web\/wp-json\/wp\/v2\/tags?post=11805"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}